{"id":12628,"count":1,"description":"","link":"https:\/\/blogs.transparent.com\/chinese\/tag\/%e8%83%bd%e6%ba%90%e6%b6%88%e8%80%97\/","name":"\u80fd\u6e90\u6d88\u8017","slug":"%e8%83%bd%e6%ba%90%e6%b6%88%e8%80%97","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"noindex, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/blogs.transparent.com\/chinese\/tag\/%e8%83%bd%e6%ba%90%e6%b6%88%e8%80%97\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.transparent.com\\\/chinese\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/12628\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blogs.transparent.com\\\/chinese#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blogs.transparent.com\\\/chinese\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blogs.transparent.com\\\/chinese\\\/tag\\\/%e8%83%bd%e6%ba%90%e6%b6%88%e8%80%97\\\/#listItem\",\"name\":\"\\u80fd\\u6e90\\u6d88\\u8017\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blogs.transparent.com\\\/chinese\\\/tag\\\/%e8%83%bd%e6%ba%90%e6%b6%88%e8%80%97\\\/#listItem\",\"position\":2,\"name\":\"\\u80fd\\u6e90\\u6d88\\u8017\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blogs.transparent.com\\\/chinese#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blogs.transparent.com\\\/chinese\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/12628\\\/#collectionpage\",\"url\":\"https:\\\/\\\/blogs.transparent.com\\\/chinese\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/12628\\\/\",\"name\":\"\\u80fd\\u6e90\\u6d88\\u8017 | Chinese Language Blog\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.transparent.com\\\/chinese\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.transparent.com\\\/chinese\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/12628\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogs.transparent.com\\\/chinese\\\/#organization\",\"name\":\"Chinese Language Blog\",\"description\":\"Language and Culture of the Chinese-Speaking World\",\"url\":\"https:\\\/\\\/blogs.transparent.com\\\/chinese\\\/\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.transparent.com\\\/chinese\\\/#website\",\"url\":\"https:\\\/\\\/blogs.transparent.com\\\/chinese\\\/\",\"name\":\"Chinese Language Blog\",\"description\":\"Language and Culture of the Chinese-Speaking World\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.transparent.com\\\/chinese\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u80fd\u6e90\u6d88\u8017 | Chinese Language Blog","description":"","canonical_url":"https:\/\/blogs.transparent.com\/chinese\/tag\/%e8%83%bd%e6%ba%90%e6%b6%88%e8%80%97\/","robots":"noindex, max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/blogs.transparent.com\/chinese\/wp-json\/wp\/v2\/tags\/12628\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/blogs.transparent.com\/chinese#listItem","position":1,"name":"Home","item":"https:\/\/blogs.transparent.com\/chinese","nextItem":{"@type":"ListItem","@id":"https:\/\/blogs.transparent.com\/chinese\/tag\/%e8%83%bd%e6%ba%90%e6%b6%88%e8%80%97\/#listItem","name":"\u80fd\u6e90\u6d88\u8017"}},{"@type":"ListItem","@id":"https:\/\/blogs.transparent.com\/chinese\/tag\/%e8%83%bd%e6%ba%90%e6%b6%88%e8%80%97\/#listItem","position":2,"name":"\u80fd\u6e90\u6d88\u8017","previousItem":{"@type":"ListItem","@id":"https:\/\/blogs.transparent.com\/chinese#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/blogs.transparent.com\/chinese\/wp-json\/wp\/v2\/tags\/12628\/#collectionpage","url":"https:\/\/blogs.transparent.com\/chinese\/wp-json\/wp\/v2\/tags\/12628\/","name":"\u80fd\u6e90\u6d88\u8017 | Chinese Language Blog","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/blogs.transparent.com\/chinese\/#website"},"breadcrumb":{"@id":"https:\/\/blogs.transparent.com\/chinese\/wp-json\/wp\/v2\/tags\/12628\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/blogs.transparent.com\/chinese\/#organization","name":"Chinese Language Blog","description":"Language and Culture of the Chinese-Speaking World","url":"https:\/\/blogs.transparent.com\/chinese\/"},{"@type":"WebSite","@id":"https:\/\/blogs.transparent.com\/chinese\/#website","url":"https:\/\/blogs.transparent.com\/chinese\/","name":"Chinese Language Blog","description":"Language and Culture of the Chinese-Speaking World","inLanguage":"en-US","publisher":{"@id":"https:\/\/blogs.transparent.com\/chinese\/#organization"}}]}},"_links":{"self":[{"href":"https:\/\/blogs.transparent.com\/chinese\/wp-json\/wp\/v2\/tags\/12628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.transparent.com\/chinese\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.transparent.com\/chinese\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.transparent.com\/chinese\/wp-json\/wp\/v2\/posts?tags=12628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}