{"id":4258,"date":"2012-01-10T08:00:28","date_gmt":"2012-01-10T12:00:28","guid":{"rendered":"https:\/\/blogs.transparent.com\/ingles\/?p=4258"},"modified":"2012-01-10T08:00:28","modified_gmt":"2012-01-10T12:00:28","slug":"expressoes-com-a-preposicao-for-parte-02","status":"publish","type":"post","link":"https:\/\/blogs.transparent.com\/ingles\/2012\/01\/10\/expressoes-com-a-preposicao-for-parte-02\/","title":{"rendered":"Express\u00f5es com a preposi\u00e7\u00e3o &#8220;for&#8221; &#8211; Parte 02"},"content":{"rendered":"<p style=\"text-align: justify\"><em>Hi, there!<\/em><\/p>\n<p style=\"text-align: justify\">Na semana passada vimos <a href=\"https:\/\/blogs.transparent.com\/br\/ingles\/intermediario\/expressoes-com-a-preposicao-for\">algumas express\u00f5es idiom\u00e1ticas com a preposi\u00e7\u00e3o <strong>for <\/strong><\/a>e hoje continuamos com mais algumas. Lembre-se de que para aprender ingl\u00eas corretamente voc\u00ea precisa revisar sempre o que j\u00e1 foi apresentado para sedimentar seus conhecimentos ainda mais. Clique aqui para revisar as primeiras express\u00f5es com a preposi\u00e7\u00e3o for.<\/p>\n<p style=\"text-align: justify\"><em>Shall we start? <\/em>(Vamos come\u00e7ar?)<\/p>\n<p style=\"text-align: justify\"><strong>for example\/instance<\/strong> &#8211; por exemplo. <em>I know a lot of people here. Fred, for example, is my co-worker. <\/em>(Conhe\u00e7o muita gente aqui. O Fred, por exemplo, trabalha comigo.)<\/p>\n<p style=\"text-align: justify\"><strong>for free<\/strong> &#8211; de gra\u00e7a. <em>They expected me to sing for free at their anniversary. Why&#8217;s that again? <\/em>(Eles esperavam que eu cantasse de gra\u00e7a no anivers\u00e1rio deles. Por qu\u00ea mesmo?)<\/p>\n<p style=\"text-align: justify\"><strong>for fun<\/strong> &#8211; de brincadeira, por prazer. <em>Guga said he&#8217;s retired and now he only plays for fun.<\/em> (Guga disse que ele se aposentou e que agora s\u00f3 joga de brincadeira.)<\/p>\n<p style=\"text-align: justify\"><strong>for good<\/strong> &#8211; para sempre. <em>If you do that you&#8217;ll lose her for good.<\/em> (Se voc\u00ea fizer isso, voc\u00ea a perder\u00e1 para sempre.)<\/p>\n<p style=\"text-align: justify\"><strong>for hire\/rent<\/strong> &#8211; aluga-se, para alugar. <em>There are four tennis courts available for hire at the hotel.<\/em> (H\u00e1 quatro quadras de t\u00eanis para alugar no hotel.)<\/p>\n<p style=\"text-align: justify\"><strong>for kicks<\/strong> &#8211; de brincadeira. <em>I just play the banjo for kicks \u2013 I\u2019m not very good at it.<\/em> (S\u00f3 toco banjo de brincadeira &#8211; n\u00e3o sou muito bom nisso.)<\/p>\n<p style=\"text-align: justify\"><strong>for love \/ money<\/strong> &#8211; por dinheiro \/ amor. <em>Would you do that for love or for money?<\/em> (Voc\u00ea faria isso por amor ou por dinheiro?)<\/p>\n<p style=\"text-align: justify\"><strong>for nothing<\/strong> &#8211; de gra\u00e7a; por nada. <em>You don&#8217;t expect me to work for you for nothing, do you? <\/em>(Voc\u00ea n\u00e3o espera que eu trabalhe para voc\u00ea de gra\u00e7a, n\u00e9?) &#8211; <em>He was not called &#8220;angel of death&#8221; for nothing.<\/em> (Ele n\u00e3o era chamado de &#8220;anjo da morte&#8221; por nada!)<\/p>\n<p style=\"text-align: justify\"><strong>for old time&#8217;s sake <\/strong>&#8211; em nome do passado, para recordar o passado. <em>How about a drink, just for old times&#8217; sake?<\/em> (Que tal um drinque, s\u00f3 para lembrar os bons tempos?)<\/p>\n<p style=\"text-align: justify\"><strong>for one&#8217;s own sake <\/strong>&#8211; para o seu pr\u00f3prio bem. <em>Don&#8217;t be mad at me. I&#8217;m just saying this for your own sake.<\/em> (N\u00e3o fique bravo comigo. Eu s\u00f3 estou dizendo isso para o seu pr\u00f3prio bem.)<\/p>\n<p style=\"text-align: justify\"><strong>for pleasure<\/strong> &#8211; por prazer. <em>He did it for pleasure, not for money.<\/em> (Ele fez por prazer, n\u00e3o por dinheiro.)<\/p>\n<p style=\"text-align: justify\"><strong>for real<\/strong> &#8211; de verdade, pra valer. <em>Is this for real? That&#8217;s what I want to know. <\/em>(\u00c9 pra valer? \u00c9 isso que eu quero saber.)<\/p>\n<p style=\"text-align: justify\">Confira na semana que vem a terceira e \u00faltima parte das express\u00f5es com a preposi\u00e7\u00e3o <strong>for<\/strong>.<\/p>\n<p style=\"text-align: justify\"><a href=\"https:\/\/blogs.transparent.com\/br\/ingles\/intermediario\/expressoes-com-a-preposicao-for\">Clique aqui <\/a>para ler a primeira parte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hi, there! Na semana passada vimos algumas express\u00f5es idiom\u00e1ticas com a preposi\u00e7\u00e3o for e hoje continuamos com mais algumas. Lembre-se de que para aprender ingl\u00eas corretamente voc\u00ea precisa revisar sempre o que j\u00e1 foi apresentado para sedimentar seus conhecimentos ainda mais. Clique aqui para revisar as primeiras express\u00f5es com a preposi\u00e7\u00e3o for. Shall we start?&hellip;<\/p>\n<p class=\"post-item__readmore\"><a class=\"btn btn--md\" href=\"https:\/\/blogs.transparent.com\/ingles\/2012\/01\/10\/expressoes-com-a-preposicao-for-parte-02\/\">Continue Reading<\/a><\/p>","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":""},"categories":[225062],"tags":[226534],"class_list":["post-4258","post","type-post","status-publish","hentry","category-intermediario","tag-artigos-gramatica"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/blogs.transparent.com\/ingles\/wp-json\/wp\/v2\/posts\/4258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.transparent.com\/ingles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.transparent.com\/ingles\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.transparent.com\/ingles\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.transparent.com\/ingles\/wp-json\/wp\/v2\/comments?post=4258"}],"version-history":[{"count":0,"href":"https:\/\/blogs.transparent.com\/ingles\/wp-json\/wp\/v2\/posts\/4258\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.transparent.com\/ingles\/wp-json\/wp\/v2\/media?parent=4258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.transparent.com\/ingles\/wp-json\/wp\/v2\/categories?post=4258"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.transparent.com\/ingles\/wp-json\/wp\/v2\/tags?post=4258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}